{"id":41990,"date":"2025-01-28T17:22:07","date_gmt":"2025-01-28T16:22:07","guid":{"rendered":"https:\/\/personal-finance.bnpparibas\/observatoire-auto-2025\/"},"modified":"2025-01-28T18:13:10","modified_gmt":"2025-01-28T17:13:10","slug":"observatoire-auto-2025","status":"publish","type":"post","link":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/","title":{"rendered":"Observatoire Auto 2025"},"content":{"rendered":"<div class=\"container\">\n<h2 class=\"wp-block-heading\">Observatoire Auto 2025 is out!<\/h2>\n<\/div>\n\n<div class=\"container\">\n<p>In 2011, L\u2019Observatoire Cetelem took an interest in the under-30s, then called the &#8220;Generation Y&#8221;.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Nearly 15 years later, it looks at Generation Z, which succeeded them, in a new survey, which assess its relationship with cars in a context of market downturn, slowing inflation and debates on the transition to electric.&nbsp;<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>Carried out in 14 countries, among 16,000 people, L&#8217;Observatoire Cetelem survey 2025 is rich in lessons.<\/p>\n<\/div>\n\n\n<div class=\"container\">\n\n    <div class=\"my-3 text-center\">\n\n        <a id=\"block_1cdfb2cff262b3edc7292071cda2ae32\" href=\"https:\/\/observatoirecetelem.com\/en\/automobile-en\/observatoire-auto-2025\"   class=\"btn btn-border\">\n            Full study\n                    <\/a>\n\n    <\/div>\n\n<\/div>\n\n<div class=\"container\">\n<h2 class=\"wp-block-heading\"><strong>Key elements in video<\/strong><\/h2>\n<\/div>\n\n<div class=\"container\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"iframe-wrapper\"><iframe title=\"Vid\u00e9o Youtube - Youth and cars: breakup or love story?\" src=\"https:\/\/www.youtube.com\/embed\/5v3xmnscWjs?feature=oembed\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n<\/div>\n\n<div class=\"container\">\n<h2 class=\"wp-block-heading\">About Observatoire Cetelem<\/h2>\n<\/div>\n\n<div class=\"container\">\n<p>Founded in 1985,&nbsp;<strong>L\u2019Observatoire Cetelem<\/strong>&nbsp;is an&nbsp;<strong>economic research and intelligence unit<\/strong>&nbsp;of the&nbsp;<strong>BNP Paribas Personal Finance group<\/strong>, headed by Flavien Neuvy.<\/p>\n<\/div>\n\n<div class=\"container\">\n<p>In what is a time of deep transformation for retail and consumption models, L\u2019Observatoire Cetelem strives&nbsp;<strong>to understand the changes affecting consumption<\/strong>. To fulfil this ambition, L\u2019Observatoire Cetelem has set up a range of tools to observe and analyse the world around us, based on diverse and complementary content described below.<\/p>\n<\/div>\n\n\n<div class=\"container\">\n\n    <div class=\"my-3 text-left\">\n\n        <a id=\"block_d4b44d9313d85c031e33e6634436d900\" href=\"https:\/\/observatoirecetelem.com\/en\/about-us\"   class=\"btn btn-border\">\n            Know more\n                    <\/a>\n\n    <\/div>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Observatoire Auto 2025 is out! In 2011, L\u2019Observatoire Cetelem took an interest in the under-30s, then called the &#8220;Generation Y&#8221;. Nearly 15 years later, it looks at Generation Z, which succeeded them, in a new survey, which assess its relationship with cars in a context of market downturn, slowing inflation and debates on the transition [&hellip;]<\/p>\n","protected":false},"author":1932,"featured_media":41986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[447],"tags":[],"class_list":["post-41990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-obs-studies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Observatoire Auto 2025 - Personal Finance<\/title>\n<meta name=\"description\" content=\"L&#039;Observatoire Cetelem a sorti sa derni\u00e8re \u00e9tude : l&#039;Observatoire Auto 2025 - les jeunes et la voiture, la fin d&#039;une belle histoire ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Observatoire Auto 2025 - Personal Finance\" \/>\n<meta property=\"og:description\" content=\"L&#039;Observatoire Cetelem a sorti sa derni\u00e8re \u00e9tude : l&#039;Observatoire Auto 2025 - les jeunes et la voiture, la fin d&#039;une belle histoire ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Personal Finance\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T16:22:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T17:13:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/personal-finance.bnpparibas\/app\/uploads\/sites\/4\/2025\/01\/obs-auto-25.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mmorisset\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mmorisset\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/\",\"url\":\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/\",\"name\":\"Observatoire Auto 2025 - Personal Finance\",\"isPartOf\":{\"@id\":\"https:\/\/personal-finance.bnpparibas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/personal-finance.bnpparibas\/app\/uploads\/sites\/4\/2025\/01\/obs-auto-25.png\",\"datePublished\":\"2025-01-28T16:22:07+00:00\",\"dateModified\":\"2025-01-28T17:13:10+00:00\",\"author\":{\"@id\":\"https:\/\/personal-finance.bnpparibas\/#\/schema\/person\/f98d1687787f01411b1b8a1dd642b49a\"},\"description\":\"L'Observatoire Cetelem a sorti sa derni\u00e8re \u00e9tude : l'Observatoire Auto 2025 - les jeunes et la voiture, la fin d'une belle histoire ?\",\"breadcrumb\":{\"@id\":\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#primaryimage\",\"url\":\"https:\/\/personal-finance.bnpparibas\/app\/uploads\/sites\/4\/2025\/01\/obs-auto-25.png\",\"contentUrl\":\"https:\/\/personal-finance.bnpparibas\/app\/uploads\/sites\/4\/2025\/01\/obs-auto-25.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/personal-finance.bnpparibas\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Observatoire Auto 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/personal-finance.bnpparibas\/#website\",\"url\":\"https:\/\/personal-finance.bnpparibas\/\",\"name\":\"Personal Finance\",\"description\":\"BNP Paribas Personal Finance\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/personal-finance.bnpparibas\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/personal-finance.bnpparibas\/#\/schema\/person\/f98d1687787f01411b1b8a1dd642b49a\",\"name\":\"mmorisset\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/personal-finance.bnpparibas\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c028291b0150e2ad22911822d7ceb3f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c028291b0150e2ad22911822d7ceb3f?s=96&d=mm&r=g\",\"caption\":\"mmorisset\"},\"url\":\"https:\/\/personal-finance.bnpparibas\/en\/author\/mmorisset\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Observatoire Auto 2025 - Personal Finance","description":"L'Observatoire Cetelem a sorti sa derni\u00e8re \u00e9tude : l'Observatoire Auto 2025 - les jeunes et la voiture, la fin d'une belle histoire ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/","og_locale":"en_US","og_type":"article","og_title":"Observatoire Auto 2025 - Personal Finance","og_description":"L'Observatoire Cetelem a sorti sa derni\u00e8re \u00e9tude : l'Observatoire Auto 2025 - les jeunes et la voiture, la fin d'une belle histoire ?","og_url":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/","og_site_name":"Personal Finance","article_published_time":"2025-01-28T16:22:07+00:00","article_modified_time":"2025-01-28T17:13:10+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/personal-finance.bnpparibas\/app\/uploads\/sites\/4\/2025\/01\/obs-auto-25.png","type":"image\/png"}],"author":"mmorisset","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mmorisset","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/","url":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/","name":"Observatoire Auto 2025 - Personal Finance","isPartOf":{"@id":"https:\/\/personal-finance.bnpparibas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#primaryimage"},"image":{"@id":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/personal-finance.bnpparibas\/app\/uploads\/sites\/4\/2025\/01\/obs-auto-25.png","datePublished":"2025-01-28T16:22:07+00:00","dateModified":"2025-01-28T17:13:10+00:00","author":{"@id":"https:\/\/personal-finance.bnpparibas\/#\/schema\/person\/f98d1687787f01411b1b8a1dd642b49a"},"description":"L'Observatoire Cetelem a sorti sa derni\u00e8re \u00e9tude : l'Observatoire Auto 2025 - les jeunes et la voiture, la fin d'une belle histoire ?","breadcrumb":{"@id":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#primaryimage","url":"https:\/\/personal-finance.bnpparibas\/app\/uploads\/sites\/4\/2025\/01\/obs-auto-25.png","contentUrl":"https:\/\/personal-finance.bnpparibas\/app\/uploads\/sites\/4\/2025\/01\/obs-auto-25.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/personal-finance.bnpparibas\/en\/observatoire-auto-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/personal-finance.bnpparibas\/en\/"},{"@type":"ListItem","position":2,"name":"Observatoire Auto 2025"}]},{"@type":"WebSite","@id":"https:\/\/personal-finance.bnpparibas\/#website","url":"https:\/\/personal-finance.bnpparibas\/","name":"Personal Finance","description":"BNP Paribas Personal Finance","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/personal-finance.bnpparibas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/personal-finance.bnpparibas\/#\/schema\/person\/f98d1687787f01411b1b8a1dd642b49a","name":"mmorisset","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/personal-finance.bnpparibas\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c028291b0150e2ad22911822d7ceb3f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c028291b0150e2ad22911822d7ceb3f?s=96&d=mm&r=g","caption":"mmorisset"},"url":"https:\/\/personal-finance.bnpparibas\/en\/author\/mmorisset\/"}]}},"_links":{"self":[{"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/posts\/41990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/users\/1932"}],"replies":[{"embeddable":true,"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/comments?post=41990"}],"version-history":[{"count":2,"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/posts\/41990\/revisions"}],"predecessor-version":[{"id":41999,"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/posts\/41990\/revisions\/41999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/media\/41986"}],"wp:attachment":[{"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/media?parent=41990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/categories?post=41990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/personal-finance.bnpparibas\/en\/wp-json\/wp\/v2\/tags?post=41990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}